{"id":5050,"date":"2019-08-28T09:00:19","date_gmt":"2019-08-28T07:00:19","guid":{"rendered":"https:\/\/isla-travel.de\/?p=5050"},"modified":"2024-09-18T17:25:45","modified_gmt":"2024-09-18T15:25:45","slug":"pomodoro-barcollante","status":"publish","type":"post","link":"https:\/\/isla-travel.de\/it\/mallorca-magazin\/tomaten-taumel\/","title":{"rendered":"Frenesia del pomodoro"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; custom_padding_last_edited=&#8220;on|phone&#8220; admin_label=&#8220;Einleitungsbereich&#8220; _builder_version=&#8220;4.24.3&#8243; z_index=&#8220;0&#8243; custom_padding=&#8220;50px||50px||true|false&#8220; custom_padding_tablet=&#8220;||20px||false|false&#8220; custom_padding_phone=&#8220;20px||20px||false|false&#8220; collapsed=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row column_structure=&#8220;2_3,1_3&#8243; use_custom_gutter=&#8220;on&#8220; make_equal=&#8220;on&#8220; _builder_version=&#8220;4.27.0&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;2_3&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;TEXT und FOTOS Hinweis&#8220; _builder_version=&#8220;4.24.3&#8243; _dynamic_attributes=&#8220;content&#8220; _module_preset=&#8220;76c1c7ae-0d81-4200-a7e6-6463f1153d95&#8243; text_font=&#8220;||||||||&#8220; custom_margin=&#8220;||||false|false&#8220; text_font_size_last_edited=&#8220;off|phone&#8220; global_colors_info=&#8220;{}&#8220;]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9jYXRlZ29yaWVzIiwic2V0dGluZ3MiOnsiYmVmb3JlIjoiPGI+UkVTU09SVDwvYj4gJm5ic3A7IFx1MjAxZSIsImFmdGVyIjoiXHUyMDFkIiwibGlua190b190ZXJtX3BhZ2UiOiJvZmYiLCJzZXBhcmF0b3IiOiIgXHUyMDIyICIsImNhdGVnb3J5X3R5cGUiOiJjYXRlZ29yeSJ9fQ==@[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.0&#8243; _dynamic_attributes=&#8220;content&#8220; _module_preset=&#8220;default&#8220; header_font_size=&#8220;34px&#8220; header_letter_spacing=&#8220;0.12em&#8220; header_font_size_tablet=&#8220;28px&#8220; header_font_size_phone=&#8220;22px&#8220; header_font_size_last_edited=&#8220;on|phone&#8220; custom_css_free_form=&#8220;selector h1 { text-transform: none !important; letter-spacing: 0.02em !important;}&#8220; global_colors_info=&#8220;{}&#8220;]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF90aXRsZSIsInNldHRpbmdzIjp7ImJlZm9yZSI6IjxoMT4iLCJhZnRlciI6IjwvaDE+In19@[\/et_pb_text][et_pb_text admin_label=&#8220;TEXT und FOTOS Hinweis&#8220; _builder_version=&#8220;4.24.3&#8243; _dynamic_attributes=&#8220;content&#8220; _module_preset=&#8220;76c1c7ae-0d81-4200-a7e6-6463f1153d95&#8243; global_colors_info=&#8220;{}&#8220;]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9kYXRlIiwic2V0dGluZ3MiOnsiYmVmb3JlIjoiTWFsbG9yY2EsIGRlbiAiLCJhZnRlciI6IiIsImRhdGVfZm9ybWF0IjoiZGVmYXVsdCIsImN1c3RvbV9kYXRlX2Zvcm1hdCI6IiJ9fQ==@[\/et_pb_text][et_pb_text admin_label=&#8220;Auszug&#8220; _builder_version=&#8220;4.24.2&#8243; _dynamic_attributes=&#8220;content&#8220; global_colors_info=&#8220;{}&#8220;]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9leGNlcnB0Iiwic2V0dGluZ3MiOnsiYmVmb3JlIjoiIiwiYWZ0ZXIiOiIiLCJ3b3JkcyI6IiIsInJlYWRfbW9yZV9sYWJlbCI6IiJ9fQ==@[\/et_pb_text][et_pb_text admin_label=&#8220;TEXT und FOTOS Hinweis&#8220; _builder_version=&#8220;4.27.0&#8243; _dynamic_attributes=&#8220;content&#8220; _module_preset=&#8220;76c1c7ae-0d81-4200-a7e6-6463f1153d95&#8243; text_font=&#8220;||||||||&#8220; text_font_size_last_edited=&#8220;off|phone&#8220; custom_css_free_form=&#8220;selector a {||  display: inline-block;||  background-color: #f2f2f2 !important;||}&#8220; global_colors_info=&#8220;{}&#8220;]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9hdXRob3IiLCJzZXR0aW5ncyI6eyJiZWZvcmUiOiI8Yj5URVhUPC9iPiAmbmJzcDsgIiwiYWZ0ZXIiOiIiLCJuYW1lX2Zvcm1hdCI6ImRpc3BsYXlfbmFtZSIsImxpbmsiOiJvZmYiLCJsaW5rX2Rlc3RpbmF0aW9uIjoiYXV0aG9yX2FyY2hpdmUifX0=@[\/et_pb_text][et_pb_text admin_label=&#8220;TEXT und FOTOS Hinweis&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;76c1c7ae-0d81-4200-a7e6-6463f1153d95&#8243; text_font=&#8220;||||||||&#8220; text_font_size_last_edited=&#8220;off|phone&#8220; custom_css_free_form=&#8220;selector a {||  display: inline-block;||  background-color: #f2f2f2 !important;||}&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><b>FOTO<\/b> \u00a0Anna Brauns, Gunnar Knechtel<\/p>\n<p>[\/et_pb_text][et_pb_code admin_label=&#8220;isla Tags&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; custom_css_free_form=&#8220;selector .isla-tags-container {||  font-size: 15px;||  letter-spacing: 1px;||  line-height: 1.7em;||  margin-bottom: 0;||  padding: 0;||}||selector .isla-tag-wrapper {||    display: inline-block;||    background-color: #f5f3f3;||    padding: 5px 7px;||    text-transform: uppercase;||    line-height: 1em;||    margin-bottom: 5px;||   font-size: 12px;||  letter-spacing: 1px;||}||selector .isla-tags-container {||  margin-bottom: 0;||  ||}&#8220; global_module=&#8220;25972527&#8243; saved_tabs=&#8220;all&#8220; global_colors_info=&#8220;{}&#8220;]<p class=\"isla-tags-container\"><span class=\"isla-tags-title\"><b>TAGS<\/b><\/span> &nbsp; <span class=\"isla-tag-wrapper\">Delikatessen<\/span> <span class=\"isla-tag-wrapper\">Essen &amp; Trinken<\/span> <span class=\"isla-tag-wrapper\">Kunst &amp; Kultur<\/span> <\/p>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.27.0&#8243; custom_padding=&#8220;|||&#8220; custom_css_main_element=&#8220;display: -webkit-box;||display: -webkit-flex;||display: -ms-flexbox;||display: flex;||-webkit-box-orient: vertical;||-webkit-box-direction: normal;||-webkit-flex-direction: column;||    -ms-flex-direction: column;||        flex-direction: column;||-webkit-box-pack: start;||-webkit-justify-content: flex-start;||    -ms-flex-pack: start;||        justify-content: flex-start;&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220; custom_css_main_element_last_edited=&#8220;on|phone&#8220; custom_css_main_element_tablet=&#8220; &#8220; custom_css_main_element_phone=&#8220; &#8222;][et_pb_text admin_label=&#8220;Zur\u00fcck zum Magazin&#8220; _builder_version=&#8220;4.27.0&#8243; link_font=&#8220;|600||on|||||&#8220; link_text_align=&#8220;right&#8220; link_text_color=&#8220;#393835&#8243; link_font_size=&#8220;13px&#8220; link_letter_spacing=&#8220;0.1em&#8220; link_line_height=&#8220;1.5em&#8220; text_orientation=&#8220;right&#8220; custom_margin_tablet=&#8220;||10px|&#8220; custom_margin_phone=&#8220;&#8220; custom_margin_last_edited=&#8220;on|tablet&#8220; link_letter_spacing_phone=&#8220;0&#8243; link_line_height_tablet=&#8220;&#8220; link_line_height_phone=&#8220;&#8220; link_line_height_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<a title=\"Rezepte aus Mallorca\" href=\"https:\/\/isla-travel.de\/mallorca-magazin\/#reportagen\"><i class=\"fas fa-angle-double-left\"><\/i> Alle <span class=\"islafont\">isla<\/span> Reportagen<\/a>[\/et_pb_text][et_pb_code admin_label=&#8220;Social Buttons&#8220; module_class=&#8220;kleinerabstand&#8220; _builder_version=&#8220;4.24.3&#8243; global_colors_info=&#8220;{}&#8220;]<ul class=\"et-social-icons isla-icons\">\n\n\n\t<li class=\"et-social-icon\">\n\t\t<a href=\"https:\/\/www.facebook.com\/islaeventmagazinmallorca\/\" class=\"icon\" target=\"_blank\" rel=\"noopener\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isla-travel.de\/wp-content\/themes\/isla-travel-design\/images\/facebook-icon.svg\" width=\"28\" height=\"30\" alt=\"isla Travel auf Facebook folgen\" \/>\n\t\t<\/a>\n\t<\/li>\n\n\n\t<li class=\"et-social-icon\">\n\t\t<a href=\"https:\/\/www.instagram.com\/isla_magazin_mallorca\/\" class=\"icon\" target=\"_blank\" rel=\"noopener\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isla-travel.de\/wp-content\/themes\/isla-travel-design\/images\/instagram-icon.svg\" width=\"28\" height=\"30\" alt=\"isla Mallorca Magazin by ISLA PASSI\u00d3 auf Instagram folgen\" \/>\n\t\t<\/a>\n\t<\/li>\n\n\n\t<li class=\"et-social-icon\">\n\t\t<a href=\"mailto:hello@isla-travel.de\" class=\"icon\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isla-travel.de\/wp-content\/themes\/isla-travel-design\/images\/mail-icon.svg\" width=\"28\" height=\"30\" alt=\"Schreiben Sie uns eine Mail!\" \/>\n\t\t<\/a>\n\t<\/li>\n\n\n<!--\t<li class=\"et-social-icon\">\n\t\t<a href=\"\" class=\"icon\">\n\t\t\t<span><\/span>\n\t\t<\/a>\n\t<\/li> -->\n\n\n<\/ul>[\/et_pb_code][et_pb_code _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; width=&#8220;100%&#8220; max_width=&#8220;360px&#8220; module_alignment=&#8220;right&#8220; custom_margin=&#8220;auto||||false|false&#8220; module_alignment_tablet=&#8220;left&#8220; module_alignment_phone=&#8220;left&#8220; module_alignment_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]\n<div id=\"review\" class=\"review-wrapper wp-review-5050 wp-review-star-type wp-review-default-template delay-animation\">\n\t\t\t\t\n\t\n\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t<div class=\"user-review-area visitors-review-area\">\n\t\t\t\t<div class=\"wp-review-user-rating wp-review-user-rating-star\"><div id=\"wp-review-star-rating-2490\" class=\"wp-review-rating-input review-star\" data-post-id=\"5050\" data-token=\"0370ff22fc\">\n\t<div class=\"wp-review-loading-msg\">\n\t\t<span class=\"animate-spin fa fa-spinner\"><\/span>\t\tSending\t<\/div>\n\n\t<div class=\"review-result-wrapper\">\n\t\t<span data-input-value=\"1\" title=\"1\/5\"><i class=\"fa fa-star\"><\/i><\/span><span data-input-value=\"2\" title=\"2\/5\"><i class=\"fa fa-star\"><\/i><\/span><span data-input-value=\"3\" title=\"3\/5\"><i class=\"fa fa-star\"><\/i><\/span><span data-input-value=\"4\" title=\"4\/5\"><i class=\"fa fa-star\"><\/i><\/span><span data-input-value=\"5\" title=\"5\/5\"><i class=\"fa fa-star\"><\/i><\/span>\t\t<div class=\"review-result\" style=\"width:0%;\">\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<input type=\"hidden\" class=\"wp-review-user-rating-val\" name=\"wp-review-user-rating-val\" value=\"0.0\" \/>\n\t<input type=\"hidden\" class=\"wp-review-user-rating-nonce\" value=\"0370ff22fc\" \/>\n\t<input type=\"hidden\" class=\"wp-review-user-rating-postid\" value=\"5050\" \/>\n<\/div>\n\n<style type=\"text\/css\">\n\t.wp-review-comment-rating #wp-review-star-rating-2490 .review-result-wrapper i {\n\t\tcolor: #f2dcae;\n\t}\n\t.wp-review-5050 #wp-review-star-rating-2490 .review-result-wrapper .review-result i {\n\t\tcolor: #f2a90c;\n\t\topacity: 1;\n\t\tfilter: alpha(opacity=100);\n\t}\n\t.wp-review-5050 #wp-review-star-rating-2490 .review-result-wrapper i {\n\t\tcolor: #f2dcae;\n\t}\n\t.wp-review-5050 .mts-user-review-star-container #wp-review-star-rating-2490 .selected i,\n\t.wp-review-5050 .user-review-area #wp-review-star-rating-2490 .review-result i,\n\t.wp-review-comment-field #wp-review-star-rating-2490 .review-result i,\n\t.wp-review-comment-rating #wp-review-star-rating-2490 .review-result i,\n\t.wp-review-user-rating #wp-review-star-rating-2490 .review-result-wrapper:hover span i,\n\t.wp-review-comment-rating #wp-review-star-rating-2490 .review-result-wrapper:hover span i {\n\t\tcolor: #f2a90c;\n\t\topacity: 1;\n\t\tfilter: alpha(opacity=100);\n\t}\n\t.wp-review-user-rating #wp-review-star-rating-2490 .review-result-wrapper span:hover ~ span i,\n\t.wp-review-comment-rating #wp-review-star-rating-2490 .review-result-wrapper span:hover ~ span i {\n\t\topacity: 1;\n\t\tcolor: #f2dcae;\n\t}\n<\/style>\n<\/div>\t\t\t\t<div class=\"user-total-wrapper\">\n\t\t\t\t\t<h5 class=\"user-review-title\">User Review<\/h5>\n\t\t\t\t\t<span class=\"review-total-box\">\n\t\t\t\t\t\t<span class=\"wp-review-user-rating-total\">0<\/span>\n\t\t\t\t\t\t<small>(<span class=\"wp-review-user-rating-counter\">0<\/span> votes)<\/small>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t<div class=\"user-review-area comments-review-area\">\n\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #f2dcae;\">\n\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:0%; color:#f2a90c;\">\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t<\/div><!-- .review-result -->\n\n\t<\/div><!-- .review-result-wrapper -->\n\t\n<\/div><!-- .review-star -->\n\t<div class=\"user-total-wrapper\">\n\t\t<span class=\"user-review-title\">Comments Rating<\/span>\n\t\t<span class=\"review-total-box\">\n\t\t\t\t\t\t<span class=\"wp-review-user-rating-total\">0<\/span>\n\t\t\t<small>(<span class=\"wp-review-user-rating-counter\">0<\/span> reviews)<\/small>\n\t\t\t<br \/>\n\t\t\t<small class=\"awaiting-response-wrapper\"><\/small>\n\t\t<\/span>\n\t<\/div>\n<\/div><!-- End .comments-review-area -->\n\n\t\n\t<\/div>\n\n<style type=\"text\/css\">\n\t.wp-review-5050.review-wrapper {\n\t\twidth: 100%;\n\t\tfloat: left;\n\t}\n\t.wp-review-5050.review-wrapper,\n\t.wp-review-5050 .review-title,\n\t.wp-review-5050 .review-desc p,\n\t.wp-review-5050 .reviewed-item p {\n\t\tcolor: #393835;\n\t}\n\t.wp-review-5050 .review-title {\n\t\tpadding-top: 15px;\n\t\tfont-weight: bold;\n\t}\n\t.wp-review-5050 .review-links a {\n\t\tcolor: #f2a90c;\n\t}\n\t.wp-review-5050 .review-links a:hover {\n\t\tbackground: #f2a90c;\n\t\tcolor: #fff;\n\t}\n\t.wp-review-5050 .review-list li,\n\t.wp-review-5050.review-wrapper {\n\t\tbackground: #ffffff;\n\t}\n\t.wp-review-5050 .review-title,\n\t.wp-review-5050 .review-list li:nth-child(2n),\n\t.wp-review-5050 .wpr-user-features-rating .user-review-title {\n\t\tbackground: #ffffff;\n\t}\n\t.wp-review-5050.review-wrapper,\n\t.wp-review-5050 .review-title,\n\t.wp-review-5050 .review-list li,\n\t.wp-review-5050 .review-list li:last-child,\n\t.wp-review-5050 .user-review-area,\n\t.wp-review-5050 .reviewed-item,\n\t.wp-review-5050 .review-links,\n\t.wp-review-5050 .wpr-user-features-rating {\n\t\tborder-color: #ffffff;\n\t}\n\t.wp-review-5050 .wpr-rating-accept-btn {\n\t\tbackground: #f2a90c;\n\t}\n\t.wp-review-5050.review-wrapper .user-review-title {\n\t\tcolor: inherit;\n\t}\n\t.wp-review-5050.review-wrapper .user-review-area .review-circle { height: 32px; }\n<\/style>\n[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Einleitungsbereich&#8220; _builder_version=&#8220;4.25.0&#8243; z_index=&#8220;0&#8243; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; collapsed=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row module_class=&#8220;vollbreite bildoben et_pb_row_fullwidth&#8220; _builder_version=&#8220;4.25.0&#8243; _module_preset=&#8220;default&#8220; z_index=&#8220;2&#8243; width=&#8220;89%&#8220; width_tablet=&#8220;80%&#8220; width_phone=&#8220;80%&#8220; width_last_edited=&#8220;on|phone&#8220; max_width=&#8220;89%&#8220; max_width_tablet=&#8220;80%&#8220; max_width_phone=&#8220;80%&#8220; max_width_last_edited=&#8220;on|phone&#8220; custom_margin=&#8220;0px|0px|50px|0px|false|true&#8220; custom_margin_tablet=&#8220;0px||35px||false|true&#8220; custom_margin_phone=&#8220;0px||25px||false|true&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; custom_padding=&#8220;0px|0px|0px|0px|true|true&#8220; custom_css_main_element=&#8220;height: 680px !important;||overflow: hidden;||width: 100% !important;||max-width: 100% !important;&#8220; global_colors_info=&#8220;{}&#8220; custom_css_main_element_last_edited=&#8220;off|tablet&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.25.0&#8243; _module_preset=&#8220;default&#8220; custom_css_main_element=&#8220;height: 100%;&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/isla-travel.de\/wp-content\/uploads\/2019\/08\/knechtel-oeko-gaertnerei-can-roseta-4352.jpg&#8220; alt=&#8220;\u00d6ko-G\u00e4rtnerei Can Roseta in Son Servera G\u00e4rtner Biel Sured. Tomatenstauden.Ramallet Tomaten&#8220; title_text=&#8220;\u00d6ko-G\u00e4rtnerei Can Roseta in Son Servera G\u00e4rtner Biel Sured. Tomatenstauden.Ramallet Tomaten&#8220; admin_label=&#8220;Breites Bild oben&#8220; module_id=&#8220;linksklebebild&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; height=&#8220;100%&#8220; custom_css_free_form=&#8220;selector img {||  object-position: top center;||}&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; module_id=&#8220;inhalt&#8220; _builder_version=&#8220;4.25.0&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; z_index=&#8220;3&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;1. Spalte&#8220; module_class=&#8220;dropcap&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]Das lieben Tomaten: Rund 1.000 Stunden lang stehen die Pflanzen im durchschnittlichen Inselsommer in der prallen Sonne. Aus dieser Energie sch\u00f6pfen sie die Kraft, die unterschiedlichsten Sorten, Formen, Gr\u00f6\u00dfen und Aromen heranreifen zu lassen. Seit die Frucht aus Amerika nach Spanien gebracht wurde, haben sich die Inselbewohner darauf spezialisiert, f\u00fcr fast jede Speise eine besondere Tomate zu z\u00fcchten. Dieses Wissen h\u00e4tten die Mallorquiner \u00fcber den Touristenboom fast vergessen. Jetzt lebt es wieder auf.<br \/>\nDas sp\u00fcrt man bei einem Besuch auf der Finca Can Roseta im Nordosten der Insel. Die knappe Notiz auf dem Einkaufszettel \u201eein Kilo Tomaten\u201c bringt Sie hier nicht weiter. [\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;2. Spalte&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]Biog\u00e4rtner Biel Sureda, ein 34-j\u00e4hriger Mann mit kr\u00e4ftigen H\u00e4nden und leiser Stimme, hilft Ihnen bei der Entscheidung. Wollen Sie einen Salat zubereiten oder eine So\u00dfe? M\u00f6chten Sie gro\u00dfe Mengen einkaufen, um die preiswerte Sommerfrucht als Wintervorrat zu trocknen oder einzukochen? Oder erwarten Sie netten Besuch aus der Heimat, dem Sie eine inseltypische Brotzeit, also ein \u201epa amb oli\u201c, versprochen haben?<br \/>\nSureda hat den Anbau von Setzlingen von Kind auf im elterlichen Betrieb bei Manacor gelernt. Sp\u00e4ter machte er sich als Bootsmechaniker selbstst\u00e4ndig. Doch mit der Krise herrschte in seiner Branche monatelang Flaute, die er nutzte, um den Eltern zu helfen. [\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;3. Spalte&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]\u201eBei einem Kurs \u00fcber den Einsatz von Chemikalien ermunterten sie mich, es einmal mit Bio-Setzlingen zu probieren, die es auf der Insel damals noch nicht gab\u201c, erz\u00e4hlt Sureda. Heute ern\u00e4hrt er mit dieser Idee seine Familie, und zwar ziemlich gesund.<br \/>\nF\u00fcr jeden Anlass gibt es die richtige, auf der Insel gez\u00fcchtete Sorte. Verschiedene Flaschentomaten (\u201etom\u00e0tiga de pruna\u201c) verfeinern gesch\u00e4lt und gekocht die Pasta oder eignen sich zum Einwecken. Roh und mit wei\u00dfen Zwiebeln und hellgr\u00fcnen Paprika kombiniert, wird die fleischige \u201eCor de bou\u201c (Ochsenherz) zum inseltypischen Tremp\u00f3-Salat. [\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Inhalt Teil 1 von 4&#8243; _builder_version=&#8220;4.25.0&#8243; z_index=&#8220;0&#8243; custom_padding=&#8220;0px||0px||false|false&#8220; collapsed=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row column_structure=&#8220;2_3,1_3&#8243; use_custom_gutter=&#8220;on&#8220; make_equal=&#8220;on&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; module_class=&#8220;beitragsbildfeature&#8220; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; custom_padding_tablet=&#8220;||0px||false|false&#8220; custom_padding_phone=&#8220;&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;2_3&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/isla-travel.de\/wp-content\/uploads\/2019\/08\/tomaten-gruppe-1.jpg&#8220; alt=&#8220;Bio-G\u00e4rtnerei auf Mallorca &#8211; Tomaten Vielfalt&#8220; admin_label=&#8220;Dynamic Featured Image &#8220; module_class=&#8220;coverbild topped&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; custom_css_main_element=&#8220;width: 100%;||height: 100%;&#8220; global_colors_info=&#8220;{}&#8220; custom_css_main_element_last_edited=&#8220;on|tablet&#8220; custom_css_main_element_tablet=&#8220;width: 100%;||height: auto !important;&#8220; custom_css_main_element_phone=&#8220;width: 100%;||height: auto;&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text admin_label=&#8220;\u00dcberschrift Beitragsbild&#8220; module_class=&#8220;headingborder&#8220; _builder_version=&#8220;4.27.0&#8243; header_2_font=&#8220;|||on|||||&#8220; header_2_font_size=&#8220;20px&#8220; header_3_font=&#8220;|||on|||||&#8220; header_3_font_size=&#8220;20px&#8220; custom_margin=&#8220;||0px|&#8220; custom_padding=&#8220;||0px|&#8220; header_2_font_size_tablet=&#8220;20px&#8220; header_2_font_size_phone=&#8220;18px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; header_3_font_size_tablet=&#8220;&#8220; header_3_font_size_phone=&#8220;18px&#8220; header_3_font_size_last_edited=&#8220;on|desktop&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>Tomaten in ihrer Vielfalt und f\u00fcr jeden Geschmack<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8220;3. Spalte&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]Und selbst bei den Cherry-Tomaten gibt es feine Unterschiede: \u201eEs gibt eine l\u00e4ngliche Sorte, die ich Dattel-Cherry-Tomate nenne, die ist s\u00fc\u00dfer und hat weniger S\u00e4ure\u201c, erkl\u00e4rt Sureda, bevor er sich einem wartenden Kunden zuwendet.<\/p>\n<p>Lloren\u00e7 Joan Santandreu ist mit seinem sechs Monate alten Sohn Jaume gekommen. Jaume schl\u00e4ft im Tragetuch auf dem Bauch, w\u00e4hrend sich der junge Vater \u00fcber verschiedene Sorten Ramallet-Tomaten informiert, die er in seinem Garten bei Santa Margalida selbst z\u00fcchten m\u00f6chte. Eigentlich h\u00e4tte Santandreu diese Kunst auch von seinem Vater \u2013 also Jaumes Opa \u2013 lernen k\u00f6nnen. Aber die Chance ist vertan: \u201eMein Vater war Bauer, bis er 35 Jahre alt war. Dann kam der Tourismusboom und er lie\u00df sich als Ausfahrer von Coca Cola anstellen. Jetzt ist er 83 Jahre alt, von der Zeit fr\u00fcher redet er nicht viel. Die Landwirtschaft, das bedeutete damals Armut.\u201c Das ist heute anders. [\/et_pb_text][et_pb_code _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<div id=\"cdecfe16f30c8f93ee22ff33d393781c4\"><\/div>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8220;on&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; _builder_version=&#8220;4.24.2&#8243; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;10px|0px|60px|0px|false|false&#8220; custom_padding_tablet=&#8220;1.5em||40px||false|false&#8220; custom_padding_phone=&#8220;&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][dipi_masonry_gallery gallery_ids=&#8220;5061,5055,5053,5065,5058,5063&#8243; title_in_lightbox=&#8220;on&#8220; columns=&#8220;3&#8243; gutter=&#8220;30&#8243; use_thumbnails=&#8220;on&#8220; columns_tablet=&#8220;&#8220; columns_phone=&#8220;2&#8243; columns_last_edited=&#8220;on|tablet&#8220; gutter_tablet=&#8220;20&#8243; gutter_phone=&#8220;&#8220; gutter_last_edited=&#8220;on|phone&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/dipi_masonry_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Inhalt Teil 2 von 4&#8243; _builder_version=&#8220;4.25.0&#8243; background_color=&#8220;#f5f3f3&#8243; custom_margin=&#8220;||0px|&#8220; custom_padding=&#8220;50px||0px||false|false&#8220; collapsed=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.25.0&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;4. Spalte&#8220; module_class=&#8220;headingborder&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; header_2_font_size=&#8220;20px&#8220; header_3_font_size=&#8220;20px&#8220; width_last_edited=&#8220;off|desktop&#8220; max_width=&#8220;68%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; max_width_last_edited=&#8220;on|phone&#8220; header_2_font_size_tablet=&#8220;20px&#8220; header_2_font_size_phone=&#8220;18px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; header_3_font_size_tablet=&#8220;20px&#8220; header_3_font_size_phone=&#8220;18px&#8220; header_3_font_size_last_edited=&#8220;on|desktop&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>Ramallet-Tomaten sind beliebt und teuer<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; _builder_version=&#8220;4.16&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;4. Spalte&#8220; module_class=&#8220;dropcap&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; header_3_letter_spacing=&#8220;0.1em&#8220; global_colors_info=&#8220;{}&#8220;]Ein mallorquinischer Haushalt, der etwas auf sich h\u00e4lt, hat sie das ganze Jahr \u00fcber im Haus. Die eher bl\u00e4sslichen und unscheinbaren Fr\u00fcchte werden schlie\u00dflich bei jeder Brotzeit aufs pa amb oli gerieben. \u201eBislang kaufe ich sie von einem Freund. Aber Bio-Ramallets sind teuer, jetzt m\u00f6chte ich versuchen, sie selbst anzupflanzen.\u201c<br \/>\nUnd klar, die \u00fcber die Jahre des Tourismus-Taumels fast vergessene Tradition solle auf Mallorca nicht verloren gehen.[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;5. Spalte&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; header_3_letter_spacing=&#8220;0.1em&#8220; global_colors_info=&#8220;{}&#8220;]Der sechsmonatige Jaume h\u00f6rt schon mal mit zu, wenn auch im Schlaf.Die Staude, so l\u00e4sst sich Santandreu vom etwa gleichaltrigen Sureda erkl\u00e4ren, m\u00fcsse er fast waagerecht in die Erde legen und nur so lange ordentlich gie\u00dfen, bis die ersten kleinen Fr\u00fcchte kommen.<br \/>\nDann hei\u00dft es, so wenig wie m\u00f6glich zu gie\u00dfen. \u201eDie Tomaten bleiben klein und lassen sich l\u00e4nger lagern.\u201c[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;6. Spalte&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; header_3_letter_spacing=&#8220;0.1em&#8220; global_colors_info=&#8220;{}&#8220;]Die Haltbarkeit \u2013 ohne K\u00fchlschrank vom Herbst \u00fcber den Winter bis zum neuen Tomatensommer \u2013 das ist neben Geschmack und Inseltradition die K\u00f6nigsdisziplin der Ramallets. Am besten gelingt die Lagerung, indem die Fr\u00fcchte bei der Ernte am letzten Glied des St\u00e4ngels abgebrochen werden. An den etwa einen Zentimeter langen St\u00e4ngeln h\u00e4ngen sie auf einen Bindfaden gef\u00e4delt oder geknotet frei in der Luft.[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Inhalt Teil 3 von 4&#8243; _builder_version=&#8220;4.24.2&#8243; background_color=&#8220;#f5f3f3&#8243; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;0px||0px|&#8220; custom_css_main_element=&#8220;z-index: 3;||position: relative;&#8220; collapsed=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;0px||0px|&#8220; custom_css_main_element=&#8220;position: relative;||z-index: 3;&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text quote_border_weight=&#8220;0px&#8220; admin_label=&#8220;Gro\u00dfe \u00dcberschrift&#8220; _builder_version=&#8220;4.27.0&#8243; text_text_color=&#8220;#333230&#8243; quote_font=&#8220;Freeland||||||||&#8220; quote_text_align=&#8220;center&#8220; quote_text_color=&#8220;#333230&#8243; quote_font_size=&#8220;107px&#8220; quote_line_height=&#8220;1.3em&#8220; header_3_text_align=&#8220;center&#8220; custom_margin=&#8220;0px||-6.3em||false|false&#8220; custom_margin_tablet=&#8220;||-6.6em||false|false&#8220; custom_margin_phone=&#8220;0px||-5.3em||false|false&#8220; custom_margin_last_edited=&#8220;on|tablet&#8220; custom_padding=&#8220;0px||0px|&#8220; quote_font_size_tablet=&#8220;60px&#8220; quote_font_size_phone=&#8220;60px&#8220; quote_font_size_last_edited=&#8220;on|tablet&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<blockquote><p>Die Ramallet-Tomate wird aufs pa amb Oli gerieben<\/p><\/blockquote>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Inhalt Teil 4 von 4&#8243; _builder_version=&#8220;4.27.0&#8243; background_color=&#8220;#f5f3f3&#8243; custom_margin=&#8220;0px|||&#8220; custom_padding=&#8220;0px|0px|0px|0px|false|false&#8220; hover_enabled=&#8220;0&#8243; custom_css_main_element=&#8220;z-index: 2;||position:relative;&#8220; collapsed=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;][et_pb_row column_structure=&#8220;1_3,2_3&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;1&#8243; make_equal=&#8220;on&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; _builder_version=&#8220;4.27.0&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; custom_padding=&#8220;||0px||false|false&#8220; custom_padding_tablet=&#8220;&#8220; custom_padding_phone=&#8220;&#8220; custom_css_main_element=&#8220;position: relative;||z-index: 2;&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; background_color=&#8220;#ffffff&#8220; custom_padding=&#8220;5%|3.5%|5%|3.5%&#8220; custom_padding_tablet=&#8220;2em|10%|3em|10%&#8220; custom_padding_phone=&#8220;2em|10%|3em|10%&#8220; custom_padding_last_edited=&#8220;on|desktop&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;\u00dcberschrift Bild unten&#8220; module_class=&#8220;headingborder&#8220; _builder_version=&#8220;4.27.0&#8243; header_3_font=&#8220;|||on|||||&#8220; header_3_font_size=&#8220;20px&#8220; custom_margin=&#8220;||0px|&#8220; custom_padding=&#8220;||0px|&#8220; header_3_font_size_tablet=&#8220;&#8220; header_3_font_size_phone=&#8220;18px&#8220; header_3_font_size_last_edited=&#8220;on|desktop&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>20 bis 30 verschiedene Sorten Ramallet-Tomaten<\/h3>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8220;beschreibung bild unten&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;||1.7em||false|false&#8220; global_colors_info=&#8220;{}&#8220;]\u201eWer sich weniger M\u00fche machen will, kann sie einfach in eine Kiste legen und die faulen Fr\u00fcchte regelm\u00e4\u00dfig aussortieren\u201c, so Sureda. Doch selbst bei den Ramallet-Tomaten unterscheiden die Mallorquiner noch einmal rund 20 bis 30 verschiedene Sorten, die jeweils ihre eigenen St\u00e4rken und Schw\u00e4chen und je nach Anbauort unterschiedliche Namen haben. Da gibt es die l\u00e4nglichen, die sich besonders lange halten, die Banyalbufar-Ramallets, die ihr Aroma am besten gegrillt entfalten, oder die platten Fr\u00fcchte, deren Stauden besonders ertragreich sind &#8230;<\/p>\n<p>Jetzt wissen Sie Bescheid. Sie wollten ein Kilo Tomaten? Also, welche Sorte darf es denn bitte sein?[\/et_pb_text][et_pb_code _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<div id=\"ccb364d75161f35291b59f7ca6d4e0290\"><\/div>\n<p>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8220;2_3&#8243; module_class=&#8220;coverbild&#8220; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; custom_padding_last_edited=&#8220;off|desktop&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/isla-travel.de\/wp-content\/uploads\/2019\/08\/knechtel-oeko-gaertnerei-can-roseta-4036.jpg&#8220; alt=&#8220;\u00d6ko-G\u00e4rtnerei Can Roseta in Son Servera G\u00e4rtner Biel Sured. Tomatenstauden. Ramallet Tomaten&#8220; title_text=&#8220;\u00d6ko-G\u00e4rtnerei Can Roseta in Son Servera G\u00e4rtner Biel Sured. Tomatenstauden. Ramallet Tomaten&#8220; admin_label=&#8220;Bild rechts&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; width=&#8220;100%&#8220; height=&#8220;100%&#8220; custom_css_main_element=&#8220;height:100%;||width:100%;&#8220; custom_css_free_form=&#8220;selector .et_pb_image_wrap {width: 100%; height: 100%;}||selector img {height: 100%; width: 100%; object-fit: cover; display: block;}&#8220; global_colors_info=&#8220;{}&#8220; custom_css_main_element_last_edited=&#8220;on|phone&#8220; custom_css_main_element_tablet=&#8220;height:auto;||width:100%;&#8220; custom_css_main_element_phone=&#8220;height:auto;||width:100%;&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8220;on&#8220; make_equal=&#8220;on&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; _builder_version=&#8220;4.27.0&#8243; background_enable_color=&#8220;off&#8220; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; custom_margin=&#8220;||0px||false|false&#8220; custom_padding=&#8220;40px|3.5%|40px|3.5%|false|true&#8220; custom_padding_tablet=&#8220;30px|10%|30px|10%|false|true&#8220; custom_padding_phone=&#8220;30px|3%||3%|false|true&#8220; custom_css_main_element=&#8220;position: relative;||z-index: 2;&#8220; global_module=&#8220;25972484&#8243; saved_tabs=&#8220;all&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.24.2&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_post_nav in_same_term=&#8220;on&#8220; prev_text=&#8220;%title&#8220; next_text=&#8220;%title&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; title_font=&#8220;||||on|||#CA7458|&#8220; title_text_color=&#8220;#CA7458&#8243; title_font_size=&#8220;16px&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_post_nav][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Kommentarbereich&#8220; _builder_version=&#8220;4.24.3&#8243; background_color=&#8220;#f5f3f3&#8243; custom_margin=&#8220;0px|||&#8220; custom_padding=&#8220;0px|0px|0px|0px|false|false&#8220; custom_css_main_element=&#8220;z-index: 2;||position:relative;&#8220; saved_tabs=&#8220;all&#8220; collapsed=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; global_module=&#8220;25972705&#8243; theme_builder_area=&#8220;post_content&#8220;][et_pb_row use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;1&#8243; make_equal=&#8220;on&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; _builder_version=&#8220;4.24.3&#8243; background_color=&#8220;#FFFFFF&#8220; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; custom_margin=&#8220;||0px||false|false&#8220; custom_padding=&#8220;5%|3.5%|0px|3.5%|false|true&#8220; custom_padding_tablet=&#8220;2em|10%|0px|10%|false|true&#8220; custom_padding_phone=&#8220;&#8220; custom_css_main_element=&#8220;position: relative;||z-index: 2;&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.24.2&#8243; background_color=&#8220;#ffffff&#8220; custom_padding=&#8220;0px|0px|0px|0px|false|true&#8220; custom_padding_tablet=&#8220;0px|0px|0px|0px|false|false&#8220; custom_padding_phone=&#8220;0px|0px|0px|0px|false|false&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text admin_label=&#8220;\u00dcberschrift&#8220; module_class=&#8220;headingborder&#8220; _builder_version=&#8220;4.27.0&#8243; _dynamic_attributes=&#8220;content&#8220; header_2_font_size=&#8220;24px&#8220; header_3_font=&#8220;|||on|||||&#8220; header_3_font_size=&#8220;20px&#8220; custom_margin=&#8220;||0px|&#8220; custom_padding=&#8220;||0px|&#8220; header_2_font_size_tablet=&#8220;22px&#8220; header_2_font_size_phone=&#8220;20px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; header_3_font_size_tablet=&#8220;&#8220; header_3_font_size_phone=&#8220;18px&#8220; header_3_font_size_last_edited=&#8220;on|desktop&#8220; custom_css_free_form=&#8220;selector h2 span { position: absolute !important; top: -9999px !important; left: -9999px !important; }&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF90aXRsZSIsInNldHRpbmdzIjp7ImJlZm9yZSI6IjxoMj5XYXMgZGVua2VuIFNpZTxzcGFuPiB6dW0gQXJ0aWtlbDogIiwiYWZ0ZXIiOiI8L3NwYW4+PzwvaDI+In19@[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; use_custom_gutter=&#8220;on&#8220; make_equal=&#8220;on&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; _builder_version=&#8220;4.27.0&#8243; background_color=&#8220;#FFFFFF&#8220; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; custom_margin=&#8220;||0px||false|false&#8220; custom_padding=&#8220;2em|3.5%|0px|3.5%|false|true&#8220; custom_padding_tablet=&#8220;|10%|0px|10%|false|true&#8220; custom_padding_phone=&#8220;2em||||false|false&#8220; custom_css_main_element=&#8220;position: relative;||z-index: 2;&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.24.2&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text admin_label=&#8220;1. Spalte&#8220; module_class=&#8220;dropcap&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<p>Wir laden Sie herzlich ein, Ihre Gedanken, Eindr\u00fccke und eigenen Erfahrungen im Kommentarbereich zu teilen.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.24.2&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text admin_label=&#8220;2. Spalte&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<p>Haben Sie in Mallorcas Nachrichten und Geschichten eigene Erinnerungen wiedergefunden, faszinierende Charaktere kennengelernt oder selbst Erlebnisse, die Sie mit uns teilen m\u00f6chten?<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.24.2&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text admin_label=&#8220;3. Spalte&#8220; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<p>Teilen Sie Ihre Eindr\u00fccke, wecken Sie Neugierde oder bringen Sie Ihre Begeisterung zum Ausdruck \u2013 jeder Austausch hier ist eine Bereicherung unserer gemeinsamen Leidenschaft f\u00fcr diese zauberhafte Insel.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;1&#8243; make_equal=&#8220;on&#8220; custom_padding_last_edited=&#8220;off|phone&#8220; _builder_version=&#8220;4.27.0&#8243; background_enable_color=&#8220;off&#8220; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;0px||90px||false|false&#8220; hover_enabled=&#8220;0&#8243; custom_css_main_element=&#8220;position: relative;||z-index: 2;&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220; sticky_enabled=&#8220;0&#8243;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.24.2&#8243; background_color=&#8220;#ffffff&#8220; custom_padding=&#8220;5%|4.5%|0px|4.5%|false|true&#8220; custom_padding_tablet=&#8220;4em|12.5%||12.5%|false|true&#8220; custom_padding_phone=&#8220;3em||0px||false|true&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220; custom_padding__hover_enabled=&#8220;off|desktop&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_comments show_avatar=&#8220;off&#8220; show_count=&#8220;off&#8220; module_class=&#8220;headingborder&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;||||||||&#8220; header_font_size=&#8220;24px&#8220; title_font=&#8220;Freeland||||||||&#8220; title_text_color=&#8220;#CA7458&#8243; hover_enabled=&#8220;0&#8243; header_font_size_tablet=&#8220;22px&#8220; header_font_size_phone=&#8220;20px&#8220; header_font_size_last_edited=&#8220;on|phone&#8220; title_font_size_tablet=&#8220;22px&#8220; title_font_size_phone=&#8220;22px&#8220; title_font_size_last_edited=&#8220;on|phone&#8220; body_font_size_tablet=&#8220;&#8220; body_font_size_phone=&#8220;&#8220; body_font_size_last_edited=&#8220;on|desktop&#8220; custom_css_free_form=&#8220;selector article, selector article.comment-body, .et_pb_comments_module.et_pb_no_avatar .comment-body {||    background-color: #f4f2f2;||    padding: 15px 15px 15px !important;||    padding-left: 15px !important;||    padding-right: 15px !important;||    border-radius: 0px 10px 10px 10px;||    margin-bottom: 1.7em;||}||selector .comment_area .comment-reply-link {||    top: 15px !important;||    right: 15px !important;||}||selector a#cancel-comment-reply-link {||    font-family: %22Brandon Grotesque%22, sans-serif;||    letter-spacing: 0;||    font-weight: 500;||    font-size: inherit;||    text-decoration: underline;||    color: #131415;||}&#8220; custom_css_reply_button=&#8220;font-size: 13px;&#8220; custom_css_new_title=&#8220;text-transform: none;||border-bottom: none;||padding-bottom: 0;||padding-top: .5em;||font-weight: 400 !important;&#8220; custom_css_submit_button=&#8220;font-size:16px;&#8220; global_colors_info=&#8220;{}&#8220; custom_css_submit_button_last_edited=&#8220;on|phone&#8220; custom_css_submit_button_phone=&#8220;font-size: 14px;&#8220; custom_css_submit_button_tablet=&#8220;font-size:16px;&#8220; theme_builder_area=&#8220;post_content&#8220; sticky_enabled=&#8220;0&#8243; custom_padding=&#8220;||||false|false&#8220; custom_margin=&#8220;||||false|false&#8220;][\/et_pb_comments][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; make_equal=&#8220;on&#8220; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;1&#8243; specialty=&#8220;on&#8220; background_color_1=&#8220;#f4f2f2&#8243; bg_img_2=&#8220;https:\/\/isla-travel.de\/wp-content\/uploads\/2018\/09\/mallorca-mietwagen.jpg&#8220; background_repeat_2=&#8220;no-repeat&#8220; padding_top_bottom_link_1=&#8220;false&#8220; padding_top_bottom_link_2=&#8220;false&#8220; padding_left_right_link_1=&#8220;false&#8220; padding_left_right_link_2=&#8220;false&#8220; padding_2_tablet=&#8220;12em||12em|&#8220; padding_2_phone=&#8220;6em||6em|&#8220; padding_2_last_edited=&#8220;on|desktop&#8220; module_class_2=&#8220;showonmobile&#8220; _builder_version=&#8220;4.25.1&#8243; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;30px||30px||true|false&#8220; global_module=&#8220;25957541&#8243; saved_tabs=&#8220;all&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;2_3&#8243; specialty_columns=&#8220;4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_row_inner _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;44px||0px|&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column_inner saved_specialty_column_type=&#8220;2_3&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Mietwagen&#8220; _builder_version=&#8220;4.24.2&#8243; text_font=&#8220;|600|||||||&#8220; header_3_font=&#8220;|700||on|||||&#8220; header_3_font_size=&#8220;35px&#8220; header_3_letter_spacing=&#8220;0.2em&#8220; max_width_last_edited=&#8220;off|&#8220; custom_margin=&#8220;||0.5em|&#8220; custom_padding=&#8220;0px|1.5em|0px|4.2em&#8220; custom_padding_tablet=&#8220;0px|1.5em|0px|3em&#8220; custom_padding_phone=&#8220;0px|1.5em|0px|2.5em&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; header_3_font_size_tablet=&#8220;30px&#8220; header_3_font_size_phone=&#8220;24px&#8220; header_3_font_size_last_edited=&#8220;on|desktop&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Mietwagen<span class=\"blindhelper\"> f\u00fcr Ihren n\u00e4chsten Urlaub buchen<\/span><\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.24.2&#8243; text_font=&#8220;|600|||||||&#8220; header_3_font=&#8220;|700||on|||||&#8220; header_3_font_size=&#8220;17px&#8220; header_3_letter_spacing=&#8220;0.2em&#8220; header_4_font=&#8220;|700||on|||||&#8220; max_width_last_edited=&#8220;off|&#8220; custom_margin=&#8220;||0.75em|&#8220; custom_padding=&#8220;0px|1.5em|0px|4.2em&#8220; custom_padding_tablet=&#8220;0px|1.5em|0px|3em&#8220; custom_padding_phone=&#8220;0px|1.5em|0px|2.5em&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; header_3_font_size_tablet=&#8220;&#8220; header_3_font_size_phone=&#8220;16px&#8220; header_3_font_size_last_edited=&#8220;on|desktop&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Nur ein Klick und Ihnen steht eine breite Auswahl bei unseren ausgesuchten und empfehlenswerten Mietwagen-Partnern zur Verf\u00fcgung.<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=&#8220;1_2,1_2&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;1&#8243; make_equal=&#8220;on&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; admin_label=&#8220;Zeile&#8220; module_class=&#8220;mietwagenboxen&#8220; _builder_version=&#8220;4.25.1&#8243; max_width_last_edited=&#8220;off|tablet&#8220; custom_padding=&#8220;|2.1em|44px|2.1em&#8220; custom_padding_tablet=&#8220;||1em||false|false&#8220; custom_padding_phone=&#8220;||0.5em||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column_inner type=&#8220;1_2&#8243; saved_specialty_column_type=&#8220;2_3&#8243; _builder_version=&#8220;4.25.1&#8243; custom_padding=&#8220;|15px||&#8220; custom_padding_tablet=&#8220;|15px||&#8220; custom_padding_phone=&#8220;|0px|0px||false|false&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220; custom_css_main_element_last_edited=&#8220;on|phone&#8220; custom_css_main_element_tablet=&#8220;width: 50%;&#8220; custom_css_main_element_phone=&#8220;width: 100%;&#8220;][et_pb_code module_class=&#8220;mietwagenbox&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#FFFFFF&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;||15px||false|false&#8220; custom_padding=&#8220;20px|20px|20px|20px|true|true&#8220; custom_css_free_form=&#8220;selector a { display: inline-block; text-decoration: none; margin: 0; padding: 0; }&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<div id=\"cce4d5617cde860846b76767f2c1d6238\"><\/div>\n<p>[\/et_pb_code][\/et_pb_column_inner][et_pb_column_inner type=&#8220;1_2&#8243; saved_specialty_column_type=&#8220;2_3&#8243; _builder_version=&#8220;4.25.1&#8243; custom_padding=&#8220;|||&#8220; custom_padding_tablet=&#8220;&#8220; custom_padding_phone=&#8220;||0px||false|false&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220; custom_css_main_element_last_edited=&#8220;on|phone&#8220; custom_css_main_element_tablet=&#8220;width: 50%;&#8220; custom_css_main_element_phone=&#8220;width: 100%;&#8220;][et_pb_code module_class=&#8220;mietwagenbox&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#FFFFFF&#8220; background_enable_image=&#8220;off&#8220; background_size=&#8220;contain&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;||15px||false|false&#8220; custom_padding=&#8220;20px|20px|20px|20px|true|true&#8220; custom_css_free_form=&#8220;selector a { display: inline-block; text-decoration: none; margin: 0; padding: 0; }&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<div id=\"c07f63e366ae6428de4bbdbe18184b4d0\"><\/div>\n<p><!-- [et_pb_line_break_holder] -->[\/et_pb_code][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_divider show_divider=&#8220;off&#8220; _builder_version=&#8220;4.16&#8243; height=&#8220;1px&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_divider][\/et_pb_column][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 amore a prima vista. Tra le tante variet\u00e0, i tipici pomodori Ramallet di Maiorca non vantano un aspetto croccante o colori vivaci. Ma quando si tratta di sapore, tradizione e conservabilit\u00e0, nessun'altra variet\u00e0 pu\u00f2 batterli.<\/p>","protected":false},"author":8,"featured_media":5060,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"2880","footnotes":""},"categories":[2092,80,77],"tags":[283,172,841],"dipi_cpt_category":[],"class_list":["post-5050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reportagen","category-mallorca-treffen","category-mallorca-geniessen","tag-delikatessen","tag-essen-auf-mallorca","tag-kunst-kultur"],"acf":[],"_links":{"self":[{"href":"https:\/\/isla-travel.de\/it\/wp-json\/wp\/v2\/posts\/5050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isla-travel.de\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/isla-travel.de\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/isla-travel.de\/it\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/isla-travel.de\/it\/wp-json\/wp\/v2\/comments?post=5050"}],"version-history":[{"count":17,"href":"https:\/\/isla-travel.de\/it\/wp-json\/wp\/v2\/posts\/5050\/revisions"}],"predecessor-version":[{"id":25972740,"href":"https:\/\/isla-travel.de\/it\/wp-json\/wp\/v2\/posts\/5050\/revisions\/25972740"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/isla-travel.de\/it\/wp-json\/wp\/v2\/media\/5060"}],"wp:attachment":[{"href":"https:\/\/isla-travel.de\/it\/wp-json\/wp\/v2\/media?parent=5050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/isla-travel.de\/it\/wp-json\/wp\/v2\/categories?post=5050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/isla-travel.de\/it\/wp-json\/wp\/v2\/tags?post=5050"},{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/isla-travel.de\/it\/wp-json\/wp\/v2\/dipi_cpt_category?post=5050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}